{"id":113,"date":"2020-10-08T07:07:10","date_gmt":"2020-10-08T07:07:10","guid":{"rendered":"https:\/\/pistonpumps.top\/agricultural-irrigation-centrifugal-double-suction-diesel-water-pump-6inch-to-32inch\/"},"modified":"2020-10-08T07:07:10","modified_gmt":"2020-10-08T07:07:10","slug":"agricultural-irrigation-centrifugal-double-suction-diesel-water-pump-6inch-to-32inch","status":"publish","type":"post","link":"https:\/\/pistonpumps.top\/es\/agricultural-irrigation-centrifugal-double-suction-diesel-water-pump-6inch-to-32inch\/","title":{"rendered":"Bomba de agua di\u00e9sel de doble succi\u00f3n centr\u00edfuga para riego agr\u00edcola de 6 a 32 pulgadas"},"content":{"rendered":"<p><img decoding=\"async\" style=\"height:auto\" title=\"Bomba de agua di\u00e9sel de doble succi\u00f3n centr\u00edfuga para riego agr\u00edcola de 6 a 32 pulgadas\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/Vacuum-pump-5.jpg\" alt=\"Agricultural Irrigation Centrifugal Double Suction Diesel Water Pump 6inch to 32inch\" \/><\/p>\n<p>\n<p><strong><em><u>\u00bfPor qu\u00e9 elegirnos?<\/u><\/em><\/strong><\/p>\n<ul>\n<li>Producci\u00f3n especializada. F\u00e1brica para una gran variedad de bombas de agua potable di\u00e9sel.<\/li>\n<li>\u00c9nfasis en la I+D para el avance<\/li>\n<li>Experimentado en el mercado nacional y extranjero.<\/li>\n<li>Pintado cuidadosamente o recubierto con polvo pl\u00e1stico para garantizar una excelente apariencia.<\/li>\n<li>Muchos a\u00f1os de servicios CZPT CZPT, Ingeniero 1 a un solo proveedor<\/li>\n<\/ul>\n<p><strong><em><u>Par\u00e1metros principales:<\/u><\/em><\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td>Di\u00e1metro<\/td>\n<td>dos de 48 pulgadas (DN50-1200 mm)<\/td>\n<\/tr>\n<tr>\n<td>Cargo por salida<\/td>\n<td>seis-18700 m<sup>3<\/sup>\/hora<\/td>\n<\/tr>\n<tr>\n<td>Llevar la cabeza<\/td>\n<td>5-10000 m<\/td>\n<\/tr>\n<tr>\n<td>Temperatura del l\u00edquido.<\/td>\n<td>M\u00e1xima ochenta \u00baC<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u00a0<br \/><strong><em><u>Resoluci\u00f3n multiobjetivo:<\/u><\/em><\/strong><br \/>\u2022 Agua nueva, agua potable de r\u00edo, agua de lluvia.<br \/>\u2022 Sustancia semis\u00f3lida y en suspensi\u00f3n<br \/>\u2022 Apuntado de pozos: alto potencial de bomba de vac\u00edo<br \/>\u2022 Combatir incendios o desarrollar una estaci\u00f3n de bombeo de mayor presi\u00f3n<br \/>\u2022 Confiabilidad las 24 horas<br \/>\u2022 Creado para entornos con temperaturas ambientales m\u00e1s altas<\/p>\n<p><strong><em><u>Prop\u00f3sitos principales:<\/u><\/em><\/strong><br \/>\u2022 Construcci\u00f3n y CZPT: apuntamiento de pozos y bombeo de sumidero<br \/>\u2022 Agua potable y residuos: bombeo excesivo y derivaci\u00f3n de t\u00e9cnicas<br \/>\u2022 Canteras y minas: bombeo de sumidero<br \/>\u2022 Crisis H2o Handle \u2013 bombeo de sumidero<br \/>\u2022 Muelles, puertos y CZPT: bombeo de sumideros y estabilizaci\u00f3n de cientos<\/p>\n<p><strong><em><u>Productos comunes:<\/u><\/em><\/strong><\/p>\n<ol>\n<li>Conjunto de motor di\u00e9sel<\/li>\n<li>Conjunto de bomba de H2O<\/li>\n<li>Unidad de acoplamiento de eje vers\u00e1til<\/li>\n<li>Pat\u00edn de montaje de metal<\/li>\n<\/ol>\n<p><strong><em><u>Equipamiento opcional:<\/u><\/em><\/strong><\/p>\n<ol>\n<li>Tanque de gasolina incorporado (se puede acceder a otro tanque de combustible diferente).<\/li>\n<li>Embrague o caja de cambios<\/li>\n<li>CZPTery<\/li>\n<li>Programa de defensa de motores y bombas de agua potable<\/li>\n<li>CZPT inicia y apaga autom\u00e1ticamente la operaci\u00f3n (ATS AMF)<\/li>\n<li>Gesti\u00f3n a distancia\/gesti\u00f3n fuera de responsabilidad\/gesti\u00f3n de ordenadores personales o control de tel\u00e9fonos m\u00f3viles<\/li>\n<li>Remolque y cubierta contra la intemperie<\/li>\n<li>Manguera de succi\u00f3n, manguera de suministro o manguera plana, tuber\u00eda PP\/PE, manguera de PVC o caucho reforzada con alambre.<\/li>\n<li>V\u00e1lvula de pie, v\u00e1lvula de compuerta, v\u00e1lvula antirretorno, v\u00e1lvula de mariposa, accesorios para tuber\u00edas y abrazaderas para mangueras.<\/li>\n<li>Se agregaron componentes de repuesto al motor y a la bomba de agua potable comparativamente.<\/li>\n<\/ol>\n<p>\u00a0<strong><em><u>Embalaje:<\/u><\/em><\/strong><em><u>\u00a0<\/u><\/em><br \/>CZPT convencional apropiado para transporte mar\u00edtimo o de larga distancia.<\/p>\n<p><strong><em><u>Fecha de env\u00edo:<\/u><\/em><\/strong><strong>\u00a0<\/strong><br \/>Rutinariamente, dentro de los 3 a 30 d\u00edas h\u00e1biles siguientes a la recepci\u00f3n del dep\u00f3sito, los tipos espec\u00edficos ser\u00e1n mencionados por dos eventos.<\/p>\n<p><strong><em><u>CZPT asegura:<\/u><\/em><\/strong><br \/>Nuestra empresa prioriza la calidad para lograr la mejor maquinaria en todo momento. Contamos con la certificaci\u00f3n ISO 9001 y cumplimos con las normas y la gesti\u00f3n.<\/p>\n<p><strong><u>S<em>servicios:<\/em><\/u><\/strong><br \/>1. Garant\u00eda de 1 a\u00f1o calendario o mil horas de trabajo para toda la m\u00e1quina, excepto para el reemplazo de piezas.<br \/>dos. Asistencia de CZPT por correo electr\u00f3nico durante todo el d\u00eda.<br \/>tres. Servicio de llamadas<br \/>4. Gu\u00eda del usuario ofrecida<br \/>5. Manual de instalaci\u00f3n para clientes de China y del extranjero.<br \/>seis. Servicios de mantenimiento y reemplazo<\/p>\n<p><strong><em><u>Hablar con los datos:<\/u><\/em><\/strong><br \/>Frank PAN (Supervisor de CZPT)<br \/>HangZhou CZPT Energ\u00eda CZPTry CO.,LTD.<br \/>http:\/\/wfsunny-machinery.en.produced-in-china.com\/<br \/>TEL\u00c9FONO: -536-8366176 FAX: -536-8366176<br \/>MOB: -13371 0571 sesenta y ocho \/ 18663676651<br \/>\u00a0                            <\/p>\n<p>\n<p><img decoding=\"async\" style=\"height:auto\" title=\"Bomba de agua di\u00e9sel de doble succi\u00f3n centr\u00edfuga para riego agr\u00edcola de 6 a 32 pulgadas\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/Vacuum-pump-5.jpg\" alt=\"Agricultural Irrigation Centrifugal Double Suction Diesel Water Pump 6inch to 32inch\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 elegirnos? F\u00e1brica especializada en la producci\u00f3n de muchos tipos de bombas de agua potable di\u00e9sel. \u00c9nfasis en I+D para el avance. Experiencia en el mercado nacional e internacional. Pintura o recubrimiento de polvo pl\u00e1stico cuidadosamente aplicados para garantizar una excelente apariencia. Muchos a\u00f1os de servicio de CZPT. CZPT, Ingeniero, proveedor \u00fanico. Par\u00e1metros principales: Di\u00e1metro 2-48 pulgadas (DN50-1200 mm). Caudal de salida 6-18700 m\u00b3\/h. Altura de elevaci\u00f3n [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[277,278,279,284,285,286],"class_list":["post-113","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-agricultural-diesel","tag-agricultural-irrigation-water-pump","tag-agricultural-pump","tag-agricultural-pump-irrigation","tag-diesel-water-pump-agricultural","tag-irrigation-water-pump-agricultural"],"_links":{"self":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/posts\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/comments?post=113"}],"version-history":[{"count":0,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/posts\/113\/revisions"}],"wp:attachment":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/media?parent=113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/categories?post=113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/tags?post=113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}