{"id":601,"date":"2020-10-11T18:10:12","date_gmt":"2020-10-11T18:10:12","guid":{"rendered":"https:\/\/pistonpumps.top\/f-1300-power-drill-pump-triplex-piston-water-pumps\/"},"modified":"2020-10-11T18:10:12","modified_gmt":"2020-10-11T18:10:12","slug":"f-1300-power-drill-pump-triplex-piston-water-pumps","status":"publish","type":"post","link":"https:\/\/pistonpumps.top\/es\/f-1300-power-drill-pump-triplex-piston-water-pumps\/","title":{"rendered":"Bomba de agua de pist\u00f3n triplex con taladro el\u00e9ctrico F-1300"},"content":{"rendered":"<p><img decoding=\"async\" style=\"height:auto\" title=\"Bomba de agua de pist\u00f3n triplex con taladro el\u00e9ctrico F-1300\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/Vacuum-pump-5.jpg\" alt=\"F-1300 Power Drill Pump Triplex Piston Water Pumps\" \/><\/p>\n<p>\n<h1>Bomba de lodo F-1300<\/h1>\n<p>La bomba de lodo de secuencia F es aplicable a la necesidad de una gran tensi\u00f3n de bombeo en el tema petrolero y una innovaci\u00f3n tecnol\u00f3gica de desplazamiento sustancial para una perforaci\u00f3n adecuada con su estructura confiable y compacta, peque\u00f1o volumen y excelente funcionalidad de operaci\u00f3n.<\/p>\n<p>La bomba de lodo de secuencia F tiene un procedimiento de mantenimiento de carrera extendida a una frecuencia reducida, lo que da como resultado una mejora en el rendimiento general de suministro de agua de manera eficaz y una prolongaci\u00f3n de la vida \u00fatil de los elementos hidrocin\u00e9ticos consumibles, el kit de succi\u00f3n de aire tiene una construcci\u00f3n avanzada y es confiable en la operaci\u00f3n para lograr el enfoque de absorci\u00f3n optimizado de la succi\u00f3n de aire en la tuber\u00eda de l\u00ednea.<\/p>\n<p>El aspecto de alimentaci\u00f3n de la bomba de la serie F adopta la lubricaci\u00f3n combinada forzada y la lubricaci\u00f3n intermitente exhibida con una lubricaci\u00f3n confiable y agregando la vida \u00fatil del procedimiento del componente de alimentaci\u00f3n.<\/p>\n<p>Esta bomba de recolecci\u00f3n es ampliamente utilizada en campos petrol\u00edferos y otros rastros de empresas industriales y mineras, operaci\u00f3n de perforaci\u00f3n de pozos y restauraci\u00f3n de pozos en campos petrol\u00edferos y otros rastros de empresas industriales y mineras, procedimiento de perforaci\u00f3n de pozos y restauraci\u00f3n de pozos, etc.<\/p>\n<p>\u00a0<\/p>\n<p>Especificaci\u00f3n primaria<\/p>\n<table cellspacing=\"0\">\n<tbody>\n<tr>\n<td colspan=\"3\">\n<p>Amable<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>Bomba de pist\u00f3n horizontal de 3 cilindros y un solo cilindro<\/p>\n<\/td>\n<td colspan=\"3\">\n<p>Tipo de engranaje<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>Equipo de espiga<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<p>Energ\u00eda nominal de entrada (kw\/hp)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>969\/1300<\/p>\n<\/td>\n<td colspan=\"3\">\n<p>Relaci\u00f3n de transmisi\u00f3n<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>cuatro.206:1<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<p>Carrera nominal (carrera\/min)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>120<\/p>\n<\/td>\n<td colspan=\"3\">\n<p>CZPT<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>Presionado y parpadeante<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<p>Duraci\u00f3n de la carrera (mm\/min)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>305\/ 12&#8243;<\/p>\n<\/td>\n<td colspan=\"3\">\n<p>Cavidad de la v\u00e1lvula<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>API-siete#<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<p>Dimensi\u00f3n del enlace del lado de succi\u00f3n<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>doce\u201d (305 mm)<\/p>\n<\/td>\n<td colspan=\"3\">\n<p>Dimensi\u00f3n del enlace del aspecto de descarga<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>Brida de cinco\u201d 5000 psi<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<p>La grasa del equipo primario<\/p>\n<\/td>\n<td colspan=\"2\" rowspan=\"2\">\n<p>24572\/54170<\/p>\n<\/td>\n<td colspan=\"3\" rowspan=\"2\">\n<p>Dimensiones del perfil (LxAnxAl)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>4426 x 3096 x 2004 mm<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"3\">\n<p>(kg\/libra)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>setenta y cuatro, veinticinco\u201d x 121,89\u201d x 78,9\u201d<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\">\n<p>Carrera\/min<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>Medida del revestimiento (mm\/pulgada),<\/p>\n<\/td>\n<td>\n<p>180<\/p>\n<\/td>\n<td>\n<p>ciento setenta<\/p>\n<\/td>\n<td>\n<p>ciento sesenta<\/p>\n<\/td>\n<td>\n<p>150<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>ciento cuarenta<\/p>\n<\/td>\n<td>\n<p>ciento treinta<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" rowspan=\"2\">\n<p>Clasificaci\u00f3n de fuerza (Mpa psi)<\/p>\n<\/td>\n<td>\n<p>dieciocho.7<\/p>\n<\/td>\n<td>\n<p>21<\/p>\n<\/td>\n<td>\n<p>23.siete<\/p>\n<\/td>\n<td>\n<p>27<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>31<\/p>\n<\/td>\n<td>\n<p>34.5<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>-2720<\/p>\n<\/td>\n<td>\n<p>-3050<\/p>\n<\/td>\n<td>\n<p>-3440<\/p>\n<\/td>\n<td>\n<p>-3915<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>-4495<\/p>\n<\/td>\n<td>\n<p>-5000<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>KW<\/p>\n<\/td>\n<td>\n<p>HP<\/p>\n<\/td>\n<td colspan=\"7\">\n<p>Desplazamiento: L\/S<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>ciento treinta<\/p>\n<\/td>\n<td>\n<p>799<\/p>\n<\/td>\n<td>\n<p>1071<\/p>\n<\/td>\n<td>\n<p>cincuenta cuarenta y dos (799)<\/p>\n<\/td>\n<td>\n<p>cuarenta y cuatro, noventa y siete (713)<\/p>\n<\/td>\n<td>\n<p>39.ochenta y tres(631)<\/p>\n<\/td>\n<td>\n<p>35.01(555)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>30.50(483)<\/p>\n<\/td>\n<td>\n<p>26.veinte(417)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>ciento veinte<\/p>\n<\/td>\n<td>\n<p>746<\/p>\n<\/td>\n<td>\n<p>mil<\/p>\n<\/td>\n<td>\n<p>46.54(737)<\/p>\n<\/td>\n<td>\n<p>41.cincuenta y uno(658)<\/p>\n<\/td>\n<td>\n<p>36.setenta y siete(583)<\/p>\n<\/td>\n<td>\n<p>32.32(512)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>28.quince(446)<\/p>\n<\/td>\n<td>\n<p>24.27(385)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>ciento diez<\/p>\n<\/td>\n<td>\n<p>692<\/p>\n<\/td>\n<td>\n<p>929<\/p>\n<\/td>\n<td>\n<p>42.66(676)<\/p>\n<\/td>\n<td>\n<p>38.05(603)<\/p>\n<\/td>\n<td>\n<p>33.setenta y uno(534)<\/p>\n<\/td>\n<td>\n<p>29.sesenta y dos(469)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>25.81(409)<\/p>\n<\/td>\n<td>\n<p>22.veinticinco(352)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>ciento<\/p>\n<\/td>\n<td>\n<p>639<\/p>\n<\/td>\n<td>\n<p>857<\/p>\n<\/td>\n<td>\n<p>38.setenta y ocho(614)<\/p>\n<\/td>\n<td>\n<p>34.cincuenta y nueve(548)<\/p>\n<\/td>\n<td>\n<p>treinta.64(485)<\/p>\n<\/td>\n<td>\n<p>26.noventa y tres(427)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>23.46(372)<\/p>\n<\/td>\n<td>\n<p>veinte.23(320)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>noventa<\/p>\n<\/td>\n<td>\n<p>586<\/p>\n<\/td>\n<td>\n<p>786<\/p>\n<\/td>\n<td>\n<p>34.90(533)<\/p>\n<\/td>\n<td>\n<p>31.trece(493)<\/p>\n<\/td>\n<td>\n<p>27.cincuenta y ocho(437)<\/p>\n<\/td>\n<td>\n<p>24.42(381)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>21.once(334)<\/p>\n<\/td>\n<td>\n<p>19.21(288)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>uno<\/p>\n<\/td>\n<td>\n<p>\u00a0<\/p>\n<\/td>\n<td>\n<p>\u00a0<\/p>\n<\/td>\n<td>\n<p>.3878(seis.147)<\/p>\n<\/td>\n<td>\n<p>.3459(5.483)<\/p>\n<\/td>\n<td>\n<p>.3064 (cuatro.857)<\/p>\n<\/td>\n<td>\n<p>.2693(4.269)<\/p>\n<\/td>\n<td colspan=\"2\">\n<p>.2346(tres.719)<\/p>\n<\/td>\n<td>\n<p>.2571 (tres.206)<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u00a0                            <\/p>\n<p>\n<p><img decoding=\"async\" style=\"height:auto\" title=\"Bomba de agua de pist\u00f3n triplex con taladro el\u00e9ctrico F-1300\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/Vacuum-pump-5.jpg\" alt=\"F-1300 Power Drill Pump Triplex Piston Water Pumps\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>La bomba de lodo de secuencia F-1300 es aplicable a la necesidad de una gran presi\u00f3n de bombeo en la industria petrolera y a la innovaci\u00f3n tecnol\u00f3gica de desplazamiento sustancial para una perforaci\u00f3n adecuada, gracias a su estructura confiable y compacta, su peque\u00f1o volumen y su excelente funcionalidad operativa. La bomba de lodo de secuencia F tiene un procedimiento de mantenimiento de carrera extendida a menor frecuencia, lo que resulta en una mejora [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[923],"class_list":["post-601","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-piston-pumps"],"_links":{"self":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/posts\/601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/comments?post=601"}],"version-history":[{"count":0,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/posts\/601\/revisions"}],"wp:attachment":[{"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/media?parent=601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/categories?post=601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pistonpumps.top\/es\/wp-json\/wp\/v2\/tags?post=601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}