{"id":806,"date":"2020-10-12T15:58:47","date_gmt":"2020-10-12T15:58:47","guid":{"rendered":"https:\/\/pistonpumps.top\/hot-sale-suncenter-brand-model-dgg28-28-1-pneumatic-driven-liquid-pump-for-burst-testing\/"},"modified":"2020-10-12T15:58:47","modified_gmt":"2020-10-12T15:58:47","slug":"hot-sale-suncenter-brand-model-dgg28-28-1-pneumatic-driven-liquid-pump-for-burst-testing","status":"publish","type":"post","link":"https:\/\/pistonpumps.top\/lo\/hot-sale-suncenter-brand-model-dgg28-28-1-pneumatic-driven-liquid-pump-for-burst-testing\/","title":{"rendered":"\u0eae\u0eb8\u0ec8\u0e99\u0e8d\u0eb5\u0ec8\u0eab\u0ecd\u0ec9 Suncenter \u0e82\u0eb2\u0e8d\u0e94\u0eb5: Dgg28 28: 1 \u0e9b\u0ecd\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0ea5\u0ebb\u0ea1\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e97\u0ebb\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0ec0\u0e9a\u0eb5\u0e94"},"content":{"rendered":"<p><img decoding=\"async\" style=\"height:auto\" title=\"\u0eae\u0eb8\u0ec8\u0e99\u0e8d\u0eb5\u0ec8\u0eab\u0ecd\u0ec9 Suncenter \u0e82\u0eb2\u0e8d\u0e94\u0eb5: Dgg28 28: 1 \u0e9b\u0ecd\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0ea5\u0ebb\u0ea1\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e97\u0ebb\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0ec0\u0e9a\u0eb5\u0e94\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/Vacuum-pump-5.jpg\" alt=\"Hot Sale Suncenter Brand Model: Dgg28 28: 1 Pneumatic Driven Liquid Pump for Burst Testing\" \/><\/p>\n<p><p>                                    <strong>\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99\u0e8d\u0eb5\u0ec8\u0eab\u0ecd\u0ec9 CZPT \u0ea5\u0eb2\u0e84\u0eb2\u0e96\u0eb7\u0e81: DGG28 28: \u0e9b\u0ecd\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e94\u0ec9\u0ea7\u0e8d CZPT \u0edc\u0eb6\u0ec8\u0e87\u0ead\u0eb1\u0e99 \u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e97\u0ebb\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0ec0\u0e9a\u0eb5\u0e94<\/strong><br \/>\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0ec3\u0eab\u0ec9\u0e97\u0ec8\u0eb2\u0e99\u0ea1\u0eb5\u0e9b\u0ecd\u0ec9\u0eb2\u0eaa\u0eb9\u0e9a\u0e99\u0ec9\u0eb3\u0ec1\u0e9a\u0e9a\u0e8d\u0eb9\u0ec9\u0e94\u0ec9\u0ea7\u0e8d\u0ea5\u0ebb\u0ea1\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0ea5\u0eb8\u0ec9\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0ebb\u0ea1\u0e9a\u0eb9\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0ec3\u0e99\u0e95\u0eb0\u0eab\u0ebc\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0ea7\u0eb1\u0e94\u0ec1\u0e97\u0e81\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a:<\/p>\n<ol>\n<li>\u0e84\u0ea7\u0eb2\u0ea1\u0ead\u0eb2\u0e94\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e82\u0ead\u0e87\u0ec1\u0eae\u0e87\u0e94\u0eb1\u0e99\u0eaa\u0eb8\u0e94\u0e97\u0ec9\u0eb2\u0e8d, \u0e81\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0eab\u0ea7 \u0eab\u0ebc\u0eb7 \u0ec1\u0eae\u0e87\u0ea1\u0ec9\u0eb2\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94. <\/li>\n<li>\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e81\u0eb1\u0e99\u0ec4\u0e94\u0ec9\u0e81\u0eb1\u0e9a\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0e8a\u0eb0\u0e99\u0eb4\u0e94, \u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99, \u0e99\u0ec9\u0eb3\u0e94\u0eb7\u0ec8\u0ea1 \u0ec1\u0ea5\u0eb0 \u0eaa\u0eb2\u0e99\u0ec0\u0e84\u0ea1\u0eb5.<\/li>\n<\/ol>\n<p>\u0e9b\u0ecd\u0ec9\u0eb2 CZPT \u0e96\u0eb7\u0e81\u0e8d\u0eb9\u0ec9\u0e94\u0ec9\u0ea7\u0e8d\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e94\u0ec9\u0ea7\u0e8d\u0ec1\u0eae\u0e87\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e88\u0eb2\u0e81 1bar \u0eab\u0eb2 8bar (\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8.5 psi \u0eab\u0eb2 116 psi) \u0ec2\u0e94\u0e8d\u0ea1\u0eb2\u0e94\u0e95\u0eb0\u0e96\u0eb2\u0e99 CZPT. \u0ec2\u0e94\u0e8d\u0e9e\u0eb7\u0ec9\u0e99\u0e96\u0eb2\u0e99\u0ec1\u0ea5\u0ec9\u0ea7\u0eab\u0ebc\u0eb1\u0e81\u0e81\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ead\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e97\u0ebd\u0e9a\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e81\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0eaa\u0ebd\u0e87\u0ec1\u0e9a\u0e9a\u0e95\u0ead\u0e9a\u0ec2\u0e95\u0ec9\u0e9a\u0ec8\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0ea1\u0eb7\u0e88\u0eb1\u0e9a\u0e82\u0ead\u0e87\u0ea5\u0eb9\u0e81\u0eaa\u0eb9\u0e9a\u0ea2\u0eb9\u0ec8\u0e88\u0eb8\u0e94\u0eaa\u0eb4\u0ec9\u0e99\u0eaa\u0eb8\u0e94\u0e96\u0eb7\u0e81\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0ec2\u0e94\u0e8d\u0ea7\u0eb2\u0ea7\u0eaa\u0eb5\u0ec8\u0e97\u0eb2\u0e87\u0e97\u0eb5\u0ec8\u0e94\u0eb3\u0ec0\u0e99\u0eb5\u0e99\u0e81\u0eb2\u0e99\u0ec2\u0e94\u0e8d\u0e99\u0eb1\u0e81\u0e9a\u0eb4\u0e99.<\/p>\n<p>\u0e9b\u0ecd\u0ec9\u0eb2 CZPT \u0ea1\u0eb5\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0ec0\u0e9b\u0eb1\u0e99\u0e82\u0ecd\u0ec9\u0e95\u0ecd\u0ec8\u0e82\u0ead\u0e87\u0e81\u0eb0\u0e9a\u0ead\u0e81\u0eaa\u0eb9\u0e9a\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec3\u0eab\u0e8d\u0ec8\u0ec4\u0e9b\u0eab\u0eb2\u0e81\u0eb0\u0e9a\u0ead\u0e81\u0eaa\u0eb9\u0e9a\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0ec0\u0eaa\u0eb1\u0ec9\u0e99\u0e9c\u0ec8\u0eb2\u0eaa\u0eb9\u0e99\u0e81\u0eb2\u0e87\u0e81\u0eb0\u0e97\u0eb1\u0e94\u0eae\u0eb1\u0e94\u0e81\u0ea7\u0ec8\u0eb2. \u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0ec1\u0ea1\u0ec8\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e82\u0ead\u0e87\u0eaa\u0ead\u0e87\u0e88\u0eb8\u0e94\u0e99\u0eb5\u0ec9 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9b\u0eb1\u0e99\u0ea7\u0eb4\u0e97\u0eb5\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81\u0e97\u0eb5\u0ec8\u0ec3\u0eab\u0e8d\u0ec8\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94. \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb9\u0e87\u0e81\u0ea7\u0ec8\u0eb2\u0e97\u0eb5\u0ec8\u0ec4\u0e94\u0ec9\u0ea1\u0eb2\u0e88\u0eb2\u0e81\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0ec1\u0eae\u0e87\u0e97\u0eb5\u0ec8\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99. \u0e95\u0ebb\u0ea7\u0ec0\u0ea5\u0e81\u0ec1\u0e9a\u0e9a CZPT \u0eaa\u0eb0\u0e97\u0ec9\u0ead\u0e99\u0ec0\u0e96\u0eb4\u0e87\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0ea5\u0eb0\u0e9a\u0eb8\u0ec4\u0ea7\u0ec9\u0e82\u0ead\u0e87\u0e9b\u0ecd\u0ec9\u0eb2, \u0ec0\u0e96\u0eb4\u0e87\u0ec1\u0ea1\u0ec8\u0e99\u0ea7\u0ec8\u0eb2\u0e82\u0ecd\u0ec9\u0ea1\u0eb9\u0e99\u0e9e\u0eb4\u0ec0\u0eaa\u0e94\u0edd\u0eb2\u0e8d\u0ec0\u0e96\u0eb4\u0e87\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e95\u0ebb\u0ea7\u0e88\u0eb4\u0e87. \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81\u0ec1\u0ea1\u0ec8\u0e99\u0e87\u0ec8\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0ec4\u0e94\u0ec9\u0ec2\u0e94\u0e8d\u0e9c\u0ec8\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0e87\u0ec8\u0eb2\u0e8d\u0e94\u0eb2\u0e8d. \u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0e84\u0eb9\u0e99\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e94\u0ec9\u0ea7\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0ec0\u0e81\u0eb1\u0e9a\u0ec4\u0ea7\u0ec9, \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7\u0e97\u0eb5\u0ec8\u0ea5\u0eb0\u0e9a\u0eb8\u0ec4\u0ea7\u0ec9\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e84\u0eb4\u0e94\u0ec4\u0ea5\u0ec8\u0ec4\u0e94\u0ec9.<\/p>\n<p>\u0e9b\u0ecd\u0ec9\u0eb2 CZPT \u0ec1\u0ea1\u0ec8\u0e99\u0e9b\u0ecd\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0eaa\u0eb5\u0e94\u0e99\u0ecd\u0ec9\u0eb2\u0e94\u0ec9\u0ea7\u0e8d\u0e95\u0ebb\u0ea7\u0ea1\u0eb1\u0e99\u0ec0\u0ead\u0e87. \u0ec2\u0e94\u0e8d\u0e9e\u0eb7\u0ec9\u0e99\u0e96\u0eb2\u0e99\u0ec1\u0ea5\u0ec9\u0ea7\u0ea1\u0eb1\u0e99\u0e9a\u0ecd\u0ec8\u0e88\u0eb3\u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ec9\u0ead\u0e87\u0ec3\u0e8a\u0ec9\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eab\u0ea5\u0ecd\u0ec8\u0ea5\u0eb7\u0ec8\u0e99\u0e97\u0ecd\u0ec8\u0eaa\u0ebb\u0ec8\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94. <br \/>\u0e99\u0ec9\u0eb3\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0e96\u0eb7\u0e81\u0eaa\u0eb9\u0e9a\u0ec4\u0eab\u0ebc\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ec4\u0e9b\u0ec3\u0e99\u0eab\u0ec9\u0ead\u0e87\u0e94\u0eb9\u0e94\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0e82\u0eb6\u0ec9\u0e99\u0e82\u0ead\u0e87\u0e81\u0eb0\u0e9a\u0ead\u0e81\u0eaa\u0eb9\u0e9a. \u0e94\u0ec9\u0ea7\u0e8d\u0e9c\u0ebb\u0e99\u0e81\u0eb2\u0e99\u0e94\u0eb9\u0e94\u0e99\u0eb5\u0ec9, \u0ea7\u0eb2\u0ea7\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e97\u0eb2\u0e87\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e88\u0eb0\u0ec0\u0e9b\u0eb5\u0e94 \u0ec1\u0ea5\u0eb0 \u0ea7\u0eb2\u0ea7\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81\u0e88\u0eb0\u0e9b\u0eb4\u0e94. \u0e81\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0eab\u0ea7\u0ea5\u0ebb\u0e87\u0e88\u0eb0\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0ea2\u0eb9\u0ec8\u0e94\u0ec9\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e99\u0ec9\u0eb3. \u0ea7\u0eb2\u0ea7\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e97\u0eb2\u0e87\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e88\u0eb0\u0e9b\u0eb4\u0e94 \u0ec1\u0ea5\u0eb0 \u0ea7\u0eb2\u0ea7\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81\u0e88\u0eb0\u0ec0\u0e9b\u0eb5\u0e94\u0ec2\u0e94\u0e8d\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e97\u0eb5\u0ec8\u0ec0\u0e81\u0eb5\u0e94\u0e82\u0eb6\u0ec9\u0e99. \u0e9b\u0ecd\u0ec9\u0eb2\u0e99\u0ec9\u0eb3 CZPT \u0e88\u0eb0\u0edd\u0eb9\u0e99\u0ea7\u0ebd\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0e9b\u0eb0\u0e88\u0eb3, \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec1\u0eae\u0e87\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99 \u0e9b\u0eb0\u0ea5\u0eb4\u0ea1\u0eb2\u0e99\u0e82\u0ead\u0e87\u0eae\u0ead\u0e9a\u0ea7\u0ebd\u0e99\u0e88\u0eb0\u0e8a\u0ec9\u0eb2\u0ea5\u0ebb\u0e87, \u0e9b\u0ecd\u0ec9\u0eb2\u0e88\u0eb0\u0ea2\u0eb8\u0e94\u0ec0\u0e9b\u0eb1\u0e99\u0e9b\u0eb0\u0e88\u0eb3\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0ec1\u0eae\u0e87\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e82\u0ead\u0e87\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec0\u0e97\u0ebb\u0ec8\u0eb2\u0e81\u0eb1\u0e99. \u0e9b\u0ecd\u0ec9\u0eb2\u0e88\u0eb0\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e95\u0ebb\u0ec9\u0e99\u0ec3\u0edd\u0ec8\u0e94\u0ec9\u0ea7\u0e8d\u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0ea5\u0ebb\u0e87\u0ec0\u0ea5\u0eb1\u0e81\u0e99\u0ec9\u0ead\u0e8d\u0e82\u0ead\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81 \u0eab\u0ebc\u0eb7 \u0e81\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99\u0e82\u0ead\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94. \u0e9b\u0eb0\u0eaa\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0eb2\u0e9a\u0e82\u0ead\u0e87\u0e9b\u0ecd\u0ec9\u0eb2\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec4\u0e94\u0ec9\u0eae\u0eb1\u0e9a\u0ead\u0eb4\u0e94\u0e97\u0eb4\u0e9e\u0ebb\u0e99\u0e88\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0ec0\u0e87\u0eb7\u0ec8\u0ead\u0e99\u0ec4\u0e82, \u0ec0\u0e8a\u0eb1\u0ec8\u0e99: \u0e81\u0eb2\u0e99\u0ec1\u0e82\u0e87\u0e95\u0ebb\u0ea7\u0e82\u0ead\u0e87\u0e97\u0ecd\u0ec8\u0ec4\u0ead\u0ec0\u0eaa\u0e8d \u0eab\u0ebc\u0eb7 \u0ea7\u0eb2\u0ea7\u0e99\u0eb3\u0e97\u0eb2\u0e87 (\u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0ec0\u0e81\u0eb5\u0e94\u0e88\u0eb2\u0e81\u0e84\u0ea7\u0eb2\u0ea1\u0e8a\u0eb8\u0ec8\u0ea1\u0e8a\u0eb7\u0ec8\u0e99\u0ec3\u0e99\u0eae\u0ec8\u0ead\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94), \u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e97\u0ecd\u0ec8\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e9a\u0ecd\u0ec8\u0e9e\u0ebd\u0e87\u0e9e\u0ecd \u0ec1\u0ea5\u0eb0 \u0e95\u0ebb\u0ea7\u0e81\u0ead\u0e87\u0e97\u0eb5\u0ec8\u0ec0\u0e9b\u0eb7\u0ec9\u0ead\u0e99. \u0ea2\u0ec8\u0eb2\u0eab\u0ebc\u0eb8\u0e94\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0e82\u0ead\u0e87\u0e9e\u0ead\u0e94\u0e97\u0eb5\u0ec8\u0ea5\u0eb0\u0e9a\u0eb8\u0ec4\u0ea7\u0ec9 \u0ec1\u0ea5\u0eb0 \u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb1\u0e9a CZPT \u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0eb0\u0e81\u0eb2\u0e99\u0e81\u0eb2\u0e99\u0ec4\u0eab\u0ebc\u0e97\u0eb5\u0ec8\u0ec1\u0e99\u0ec8\u0e99\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0e9a\u0ecd\u0ec8\u0ec4\u0e94\u0ec9\u0eaa\u0eb0\u0ec1\u0e94\u0e87\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0e95\u0eb2\u0e95\u0eb0\u0ea5\u0eb2\u0e87.<\/p>\n<p><strong>\u0ec1\u0ead\u0eb1\u0e9a\u0e9e\u0ea5\u0eb4\u0ec0\u0e84\u0e8a\u0eb1\u0e99\u0e9b\u0eb0\u0e81\u0ead\u0e9a\u0ea1\u0eb5:<\/strong><br \/>\u00a0<\/p>\n<ol>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0e81\u0ea7\u0e94\u0e84\u0eb1\u0e94\u0e81\u0ead\u0e87\u0ec1\u0e9a\u0e9a\u0ea5\u0eb0\u0ec0\u0e9a\u0eb5\u0e94 (\u0ec4\u0eae\u0ec2\u0e94\u0ea3\u0eaa\u0eb0\u0ec1\u0e95\u0e95\u0eb4\u0e81)<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0e8d\u0eb6\u0e94\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\/\u0e81\u0eb2\u0e99\u0edc\u0eb5\u0e9a\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0e8d\u0ebb\u0e81\/\u0e81\u0eb2\u0e99\u0e8d\u0ebb\u0e81<\/li>\n<li>\u00a0\u0ea1\u0eb7\u0e88\u0eb1\u0e9a\u0e95\u0ebb\u0ea7\u0e81\u0eb0\u0e95\u0eb8\u0ec9\u0e99\u0ea7\u0eb2\u0ea7<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0ec0\u0e9b\u0eb5\u0e94\u0ec3\u0e8a\u0ec9\u0e81\u0eb0\u0e9a\u0ead\u0e81\u0eaa\u0eb9\u0e9a CZPT<\/li>\n<li>\u00a0\u0edc\u0ec8\u0ea7\u0e8d\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e81\u0eb2\u0e99\u0ec2\u0eab\u0ebc\u0e94\u0ec0\u0e81\u0eb5\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e9b\u0ead\u0e94\u0ec4\u0e9e<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0e94\u0eb6\u0e87\u0ea5\u0eb9\u0e81\u0e81\u0eb4\u0ec9\u0e87<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0ea7\u0eb1\u0e94\u0ec1\u0e97\u0e81<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0eab\u0ea5\u0ecd\u0ec8\u0ea5\u0eb7\u0ec8\u0e99 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0eaa\u0eb5\u0e94\u0e9e\u0ebb\u0ec8\u0e99 CZPT<\/li>\n<li>\u00a0\u0e81\u0eb2\u0e99\u0ec2\u0ead\u0e99\u0ead\u0eb2\u0e8d\u0ec1\u0e81\u0eb1\u0eaa\u0ec1\u0eab\u0ebc\u0ea7<\/li>\n<\/ol>\n<p><strong>\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e97\u0eb5\u0ec8\u0eaa\u0eb3\u0e84\u0eb1\u0e99\u0e9b\u0eb0\u0e81\u0ead\u0e9a\u0ea1\u0eb5: <\/strong><br \/>\u00a0<\/p>\n<ol>\n<li>\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0ead\u0eb1\u0e94 - \u0e9a\u0ecd\u0ec8\u0e88\u0eb3\u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ec9\u0ead\u0e87\u0ec3\u0e8a\u0ec9\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2 (\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0e81\u0eb1\u0e9a CZPT \u0e97\u0ebb\u0ec8\u0ea7\u0ec4\u0e9b)<\/li>\n<li>\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e8d\u0eb7\u0e94\u0ead\u0eb2\u0e8d\u0eb8\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e87\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e9b\u0ecd\u0ec9\u0eb2, \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e84\u0ea7\u0e99\u0e88\u0eb0 <\/li>\n<\/ol>\n<p>\u0e9a\u0ecd\u0ec8\u0ec0\u0e81\u0eb5\u0e99 8 \u0e9a\u0eb2<\/p>\n<ol>\n<li>\u0e9a\u0ecd\u0ec8\u0e88\u0eb3\u0ec0\u0e9b\u0eb1\u0e99\u0e95\u0ec9\u0ead\u0e87\u0ec3\u0e8a\u0ec9\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0eab\u0ea5\u0ecd\u0ec8\u0ea5\u0eb7\u0ec8\u0e99\u0e82\u0ead\u0e87\u0eaa\u0eb2\u0e8d\u0e81\u0eb2\u0e99\u0e9a\u0eb4\u0e99 <\/li>\n<li>\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ec0\u0e96\u0eb4\u0e87 640Mpa (6400 bar)\u00a0 <\/li>\n<li>\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0ec1\u0e9a\u0e9a\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0e8a\u0eb0\u0e99\u0eb4\u0e94\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e97\u0eb5\u0ec8\u0ec1\u0e95\u0e81\u0e95\u0ec8\u0eb2\u0e87\u0e81\u0eb1\u0e99<\/li>\n<li>\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0ec0\u0eae\u0eb1\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0ea2\u0eb1\u0e99\u0ec3\u0e99\u0e95\u0ebb\u0ea7\u0ec3\u0e99\u0eae\u0eb8\u0ec8\u0e99\u0eaa\u0ec8\u0ea7\u0e99\u0ec3\u0eab\u0e8d\u0ec8 <\/li>\n<li>\u0e87\u0ec8\u0eb2\u0e8d\u0e95\u0ecd\u0ec8\u0e81\u0eb2\u0e99\u0e95\u0eb1\u0ec9\u0e87\u0e84\u0ec8\u0eb2, \u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81 \u0ec1\u0ea5\u0eb0 \u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0ec4\u0ea7\u0ec9<\/li>\n<li>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0ea5\u0eb2\u0e84\u0eb2 \/ \u0e81\u0eb2\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0e97\u0eb5\u0ec8\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1 <\/li>\n<li>\u0e9a\u0ecd\u0ec8\u0ea1\u0eb5\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ec8\u0ebd\u0e87\u0e95\u0ecd\u0ec8\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0ec9\u0ead\u0e99, \u0ec1\u0e9b\u0ea7\u0ec4\u0e9f \u0eab\u0ebc\u0eb7 \u0e9b\u0eb0\u0e81\u0eb2\u0e8d\u0ec4\u0e9f \u0ec1\u0ea5\u0eb0 \u0e9b\u0ec9\u0ead\u0e87\u0e81\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0ec0\u0e9a\u0eb5\u0e94 <\/li>\n<li>\u0e81\u0eb2\u0e99\u0e8d\u0eb6\u0e94\u0ec1\u0eae\u0e87\u0e82\u0ead\u0e87 CZPT, \u0e9a\u0ecd\u0ec8\u0ea7\u0ec8\u0eb2\u0e88\u0eb0\u0ec0\u0e9b\u0eb1\u0e99\u0eaa\u0eb2\u0ec0\u0eab\u0e94\u0e82\u0ead\u0e87\u0ec1\u0eae\u0e87\u0eab\u0ebc\u0eb8\u0e94\u0ea5\u0ebb\u0e87, \u0e9b\u0ecd\u0ec9\u0eb2 CZPT \u0e88\u0eb0\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e95\u0ebb\u0ec9\u0e99\u0ec2\u0e94\u0e8d\u0ead\u0eb1\u0e94\u0e95\u0eb0\u0ec2\u0e99\u0ea1\u0eb1\u0e94, \u0eae\u0eb1\u0e81\u0eaa\u0eb2\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0e82\u0ead\u0e87\u0ea7\u0ebb\u0e87\u0ec1\u0eab\u0ea7\u0e99\u0ea2\u0ec8\u0eb2\u0e87\u0e95\u0ecd\u0ec8\u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87<\/li>\n<\/ol>\n<p><strong>\u0e9b\u0ec9\u0eb3\u0eaa\u0eb9\u0e9a\u0e99\u0ec9\u0eb3\u0e8a\u0eb8\u0e94 DGG (\u0eab\u0ebb\u0ea7\u0eaa\u0eb9\u0e9a\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e94\u0ec8\u0ebd\u0ea7, \u0ead\u0ead\u0e81\u0ea5\u0eb4\u0e94\u0e94\u0ebd\u0ea7)<\/strong><\/p>\n<ol>\n<li>\u0e9b\u0ecd\u0ec9\u0eb2 DGG \u0ea1\u0eb5\u0ec2\u0e84\u0e87\u0ead\u0eb2\u0ea5\u0eb9\u0ea1\u0eb5\u0e99\u0ebd\u0ea1 \u0ec1\u0ea5\u0eb0 \u0ea7\u0eb1\u0e94\u0eaa\u0eb0\u0e94\u0eb8\u0e97\u0eb5\u0ec8\u0ec0\u0eae\u0eb1\u0e94\u0e94\u0ec9\u0ea7\u0e8d\u0ec2\u0ea5\u0eab\u0eb0\u0eaa\u0eb0\u0ec1\u0e95\u0e99\u0ec0\u0ea5\u0e94 \u0eab\u0ebc\u0eb7 \u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0e81\u0eb2\u0e81\u0e9a\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0e9b\u0ebd\u0e81\u0e8a\u0eb8\u0ec8\u0ea1.<\/li>\n<\/ol>\n<p>\u00a0\u00a0\u0e82\u0eb6\u0ec9\u0e99\u0e81\u0eb1\u0e9a\u0e99\u0ec9\u0eb3\u0ea2\u0eb2\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e95\u0ec8\u0eb2\u0e87\u0ec6. CZPT \u0e82\u0ead\u0e87\u0ec2\u0ea5\u0eab\u0eb0\u0eaa\u0eb0\u0ec1\u0e95\u0e99\u0ec0\u0ea5\u0e94, \u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ec0\u0e9b\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ec0\u0ea5\u0eb7\u0ead\u0e81\u0e97\u0eb5\u0ec8\u0e94\u0eb5\u0ec0\u0ea5\u0eb5\u0e94<br \/>\u0e82\u0ead\u0e87\u0e8a\u0ead\u0e9a\u0ec1\u0ea7\u0e99\u0ec9\u0eb3. \u0e9b\u0eb0\u0e97\u0eb1\u0e9a\u0e95\u0eb2\u0e97\u0eb5\u0ec8\u0ea1\u0eb5\u0e84\u0eb8\u0e99\u0e99\u0eb0\u0e9e\u0eb2\u0e9a\u0e94\u0eb5, \u0ead\u0eb2\u0e8d\u0eb8\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e87\u0eb2\u0e99\u0e9b\u0eb0\u0e88\u0eb3\u0ea7\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e8d\u0eb2\u0ea7\u0e99\u0eb2\u0e99.<\/p>\n<p><strong><\/p>\n<p>\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0 CZPT<\/strong><br \/>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99<\/td>\n<td>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99<\/td>\n<td>\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn P<sub>\u0ea5<\/sub> <\/td>\n<td>\u0ea7\u0eb4\u0e97\u0eb5\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81<\/td>\n<td>MAX Outlet<br \/>\u0ec1\u0eae\u0e87 (\u0e9a\u0eb2)*<\/td>\n<td>\u0e81\u0eb2\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0e97\u0eb2\u0e87\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7<\/td>\n<td>\u0e81\u0eb2\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0e97\u0ecd\u0ec8\u0ea5\u0eb0\u0e9a\u0eb2\u0e8d\u0e99\u0ec9\u0eb3<\/td>\n<td>\u0e81\u0eb2\u0e99\u0ec4\u0eab\u0ebc\u0ea7\u0ebd\u0e99\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 (\u0ea5\u0eb4\u0e94\/\u0e99\u0eb2\u0e97\u0eb5) <\/td>\n<\/tr>\n<tr>\n<td>DGG6<\/td>\n<td>6:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0ead\u0e87-8 \u0e9a\u0eb2<\/td>\n<td>6XP<sub>\u0ea5<\/sub><\/td>\n<td>\u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0ec1\u0e9b\u0e94<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT1\/2<\/td>\n<td>29.\u0ec0\u0e81\u0ebb\u0ec9\u0eb2\u0eaa\u0eb4\u0e9a\u0ec0\u0ead\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td>DGG10<\/td>\n<td>10:1<\/td>\n<td>\u0eaa\u0ead\u0e87\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>10XP<sub>\u0ea5<\/sub><\/td>\n<td>\u0ec1\u0e9b\u0e94\u0eaa\u0eb4\u0e9a<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>\u0eaa\u0eb4\u0e9a\u0ec1\u0e9b\u0e94. \u0ec1\u0e9b\u0e94\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8<\/td>\n<\/tr>\n<tr>\n<td>DGG16<\/td>\n<td>16:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-8 \u0e9a\u0eb2<\/td>\n<td>16XP<sub>\u0ea5<\/sub><\/td>\n<td>128<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT1\/2<\/td>\n<td>\u0eaa\u0eb4\u0e9a\u0eaa\u0ead\u0e87.42<\/td>\n<\/tr>\n<tr>\n<td>DGG28<\/td>\n<td>28:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-8 \u0e9a\u0eb2<\/td>\n<td>28XP<sub>\u0ea5<\/sub><\/td>\n<td>224<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>7.\u0eaa\u0eb4\u0e9a\u0ec0\u0ead\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td>DGG40<\/td>\n<td>40:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>40XP<sub>\u0ea5<\/sub><\/td>\n<td>320<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>4.89<\/td>\n<\/tr>\n<tr>\n<td>DGG64<\/td>\n<td>64:1<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>64XP<sub>\u0ea5<\/sub><\/td>\n<td>512<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT3\/8<\/td>\n<td>\u0eaa\u0eb2\u0ea1.08<\/td>\n<\/tr>\n<tr>\n<td>DGG80<\/td>\n<td>80:1<\/td>\n<td>\u0eaa\u0ead\u0e87-8 \u0e9a\u0eb2<\/td>\n<td>80XP<sub>\u0ea5<\/sub><\/td>\n<td>640<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT3\/\u0ec1\u0e9b\u0e94<\/td>\n<td>2. \u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8<\/td>\n<\/tr>\n<tr>\n<td>DGG100<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d:1<\/td>\n<td>\u0eaa\u0ead\u0e87-8 \u0e9a\u0eb2<\/td>\n<td>100XP<sub>\u0ea5<\/sub><\/td>\n<td>800<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT3\/8<\/td>\n<td>1.92<\/td>\n<\/tr>\n<tr>\n<td>DGG130<\/td>\n<td>130:1<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>130XP<sub>\u0ea5<\/sub><\/td>\n<td>1040<\/td>\n<td>NPT1\/2<\/td>\n<td>M14X1.5<\/td>\n<td>1. \u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0ec0\u0e88\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td>DGG175<\/td>\n<td>175:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0ead\u0e87\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>175XP<sub>\u0ea5<\/sub><\/td>\n<td>1400<\/td>\n<td>NPT3\/\u0ec1\u0e9b\u0e94<\/td>\n<td>M14X1.5<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87. \u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8<\/td>\n<\/tr>\n<tr>\n<td>DGG255<\/td>\n<td>255:1<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>255XP<sub>\u0ea5<\/sub><\/td>\n<td>2040<\/td>\n<td>NPT1\/\u0eaa\u0eb5\u0ec8<\/td>\n<td>M14X1.\u0eab\u0ec9\u0eb2<\/td>\n<td>.75<\/td>\n<\/tr>\n<tr>\n<td>DGG400<\/td>\n<td>400:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-8 \u0e9a\u0eb2<\/td>\n<td>400XP<sub>\u0ea5<\/sub><\/td>\n<td>3200<\/td>\n<td>NPT1\/\u0eaa\u0eb5\u0ec8<\/td>\n<td>M14X1.5<\/td>\n<td>.\u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0ec1\u0e9b\u0e94<\/td>\n<\/tr>\n<tr>\n<td>DGG510<\/td>\n<td>510:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0ead\u0e87\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>510XP<sub>\u0ea5<\/sub><\/td>\n<td>4080<\/td>\n<td>NPT1\/\u0eaa\u0eb5\u0ec8<\/td>\n<td>M14X1.5<\/td>\n<td>.\u0eab\u0ebb\u0e81\u0eaa\u0eb4\u0e9a\u0eab\u0ec9\u0eb2<\/td>\n<\/tr>\n<tr>\n<td>DGG800<\/td>\n<td>800:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0ead\u0e87-8 \u0e9a\u0eb2<\/td>\n<td>800XP<sub>\u0ea5<\/sub><\/td>\n<td>6400<\/td>\n<td>NPT1\/\u0eaa\u0eb5\u0ec8<\/td>\n<td>M14X1.\u0eab\u0ec9\u0eb2<\/td>\n<td>.\u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0eaa\u0ead\u0e87<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u0ec1\u0eae\u0e87\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7\u0e97\u0eb5\u0ec8\u0ead\u0ead\u0e81 = \u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn * \u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0eaa\u0eb5\u0ea1<br \/>\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e8d\u0eb7\u0e94\u0ead\u0eb2\u0e8d\u0eb8\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e87\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e9b\u0eb1\u0eca\u0ea1, \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e82\u0ead\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0e82\u0eb1\u0e9a\u0e95\u0ec9\u0ead\u0e87\u0e9a\u0ecd\u0ec8\u0ec0\u0e81\u0eb5\u0e99 8 \u0e9a\u0eb2<\/p>\n<p><strong>\u0e9b\u0ecd\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0ea5\u0eb3\u0e94\u0eb1\u0e9a DGGD (\u0eab\u0ebb\u0ea7\u0eaa\u0eb9\u0e9a\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0ec1\u0e9a\u0e9a\u0eaa\u0ead\u0e87\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a, \u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0e94\u0ec8\u0ebd\u0ea7)<\/strong><br \/>\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ea1\u0eb5\u0ea5\u0eb1\u0e81\u0eaa\u0eb0\u0e99\u0eb0\u0e84\u0ec9\u0eb2\u0e8d\u0e84\u0eb7\u0e81\u0eb1\u0e99\u0e81\u0eb1\u0e9a\u0e9b\u0ecd\u0ec9\u0eb2 DGG \u0e97\u0eb5\u0ec8\u0ead\u0ead\u0e81\u0ea5\u0eb4\u0e94\u0e94\u0ec8\u0ebd\u0ea7, \u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0eab\u0ebb\u0ea7\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0e97\u0eb2\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e94\u0ebd\u0ea7, <br \/>\u0ec1\u0e95\u0ec8\u0e9e\u0ea7\u0e81\u0ea1\u0eb1\u0e99\u0ea1\u0eb5\u0e81\u0eb2\u0e99\u0ec0\u0e95\u0eb1\u0ec9\u0e99\u0e82\u0ead\u0e87\u0eab\u0ebb\u0ea7\u0ec3\u0e88\u0edc\u0ec9\u0ead\u0e8d\u0e81\u0ea7\u0ec8\u0eb2\u0eab\u0ebc\u0eb2\u0e8d \u0ec1\u0ea5\u0eb0 \u0ec3\u0eab\u0ec9\u0e81\u0eb0\u0ec1\u0eaa\u0e9b\u0eb0\u0ea1\u0eb2\u0e99 50 % \u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2.<\/p>\n<p><strong>\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0 CZPT<\/strong><br \/>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99<\/td>\n<td>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99<\/td>\n<td>\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn P<sub>\u0ea5<\/sub> <\/td>\n<td>\u0eaa\u0eb9\u0e94\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e9b\u0eb0\u0ec0\u0ea1\u0eb5\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81<\/td>\n<td>MAX Outlet<br \/>\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87 (\u0e9a\u0eb2)*<\/td>\n<td>\u0e81\u0eb2\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0e97\u0eb2\u0e87\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7<\/td>\n<td>\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb3\u0e9e\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7<\/td>\n<td>\u0e81\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 (\u0ea5\u0eb4\u0e94\/\u0e99\u0eb2\u0e97\u0eb5)**<\/td>\n<\/tr>\n<tr>\n<td>DGGD4<\/td>\n<td>4:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0ead\u0e87\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>4XP<sub>\u0ea5<\/sub><\/td>\n<td>32<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT1\/2<\/td>\n<td>70.00<\/td>\n<\/tr>\n<tr>\n<td>DGGD6<\/td>\n<td>6:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>6XP<sub>\u0ea5<\/sub><\/td>\n<td>48<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT1\/2<\/td>\n<td>48. \u0eab\u0ebb\u0e81\u0eaa\u0eb4\u0e9a<\/td>\n<\/tr>\n<tr>\n<td>DGGD10<\/td>\n<td>\u0eaa\u0eb4\u0e9a:1<\/td>\n<td>\u0eaa\u0ead\u0e87-8 \u0e9a\u0eb2<\/td>\n<td>10XP<sub>\u0ea5<\/sub><\/td>\n<td>80<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>30.\u0eab\u0ebb\u0e81\u0eaa\u0eb4\u0e9a\u0ec0\u0ead\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td>DGGD16<\/td>\n<td>\u0eaa\u0eb4\u0e9a\u0eab\u0ebb\u0e81:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0ead\u0e87-8 \u0e9a\u0eb2<\/td>\n<td>16XP<sub>\u0ea5<\/sub><\/td>\n<td>128<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT1\/2<\/td>\n<td>19. \u0ec0\u0e88\u0eb1\u0e94\u0eaa\u0eb4\u0e9a\u0eaa\u0eb2\u0ea1<\/td>\n<\/tr>\n<tr>\n<td>DGGD28<\/td>\n<td>28:1<\/td>\n<td>\u0eaa\u0ead\u0e87\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>28XP<sub>\u0ea5<\/sub><\/td>\n<td>224<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT1\/2<\/td>\n<td>\u0eaa\u0eb4\u0e9a\u0ec0\u0ead\u0eb1\u0e94.\u0eaa\u0eb2\u0ea1\u0eaa\u0eb4\u0e9a<\/td>\n<\/tr>\n<tr>\n<td>DGGD40<\/td>\n<td>\u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>40XP<sub>\u0ea5<\/sub><\/td>\n<td>320<\/td>\n<td>NPT1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT3\/8<\/td>\n<td>\u0ec0\u0e88\u0eb1\u0e94.69<\/td>\n<\/tr>\n<tr>\n<td>DGGD64<\/td>\n<td>\u0eab\u0ebb\u0e81\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-8 \u0e9a\u0eb2<\/td>\n<td>64XP<sub>\u0ea5<\/sub><\/td>\n<td>512<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT3\/\u0ec1\u0e9b\u0e94<\/td>\n<td>4.\u0ec0\u0e81\u0ebb\u0ec9\u0eb2\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8<\/td>\n<\/tr>\n<tr>\n<td>DGGD80<\/td>\n<td>80:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0ead\u0e87\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>80XP<sub>\u0ea5<\/sub><\/td>\n<td>640<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT3\/\u0ec1\u0e9b\u0e94<\/td>\n<td>\u0eaa\u0eb2\u0ea1. \u0ec0\u0e81\u0ebb\u0ec9\u0eb2\u0eaa\u0eb4\u0e9a\u0eab\u0ebb\u0e81<\/td>\n<\/tr>\n<tr>\n<td>DGGD100<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d:1<\/td>\n<td>\u0eaa\u0ead\u0e87\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>100XP<sub>\u0ea5<\/sub><\/td>\n<td>800<\/td>\n<td>NPT1\/2<\/td>\n<td>NPT3\/8<\/td>\n<td>\u0eaa\u0eb2\u0ea1. \u0eaa\u0eb4\u0e9a\u0eaa\u0eb2\u0ea1<\/td>\n<\/tr>\n<tr>\n<td>DGGD130<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d\u0eaa\u0eb2\u0ea1\u0eaa\u0eb4\u0e9a:1<\/td>\n<td>2-8 \u0e9a\u0eb2<\/td>\n<td>130XP<sub>\u0ea5<\/sub><\/td>\n<td>1040<\/td>\n<td>NPT1\/2<\/td>\n<td>M14*1.\u0eab\u0ec9\u0eb2<\/td>\n<td>2.40<\/td>\n<\/tr>\n<tr>\n<td>DGGD175<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d\u0ec0\u0e88\u0eb1\u0e94\u0eaa\u0eb4\u0e9a\u0eab\u0ec9\u0eb2:1<\/td>\n<td>2-8 \u0e9a\u0eb2<\/td>\n<td>175XP<sub>\u0ea5<\/sub><\/td>\n<td>1400<\/td>\n<td>NPT3\/\u0ec1\u0e9b\u0e94<\/td>\n<td>M14*1.\u0eab\u0ec9\u0eb2<\/td>\n<td>1.81<\/td>\n<\/tr>\n<tr>\n<td>DGGD255<\/td>\n<td>255:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>255XP<sub>\u0ea5<\/sub><\/td>\n<td>2040<\/td>\n<td>NPT1\/\u0eaa\u0eb5\u0ec8<\/td>\n<td>M14*1.\u0eab\u0ec9\u0eb2<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87.23<\/td>\n<\/tr>\n<tr>\n<td>DGGD400<\/td>\n<td>\u0eaa\u0eb5\u0ec8\u0eae\u0ec9\u0ead\u0e8d:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>2-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>400XP<sub>\u0ea5<\/sub><\/td>\n<td>3200<\/td>\n<td>NPT1\/\u0eaa\u0eb5\u0ec8<\/td>\n<td>M14*1.5<\/td>\n<td>.\u0ec0\u0e88\u0eb1\u0e94\u0eaa\u0eb4\u0e9a\u0ec0\u0e81\u0ebb\u0ec9\u0eb2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u0ec1\u0eae\u0e87\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7\u0e97\u0eb5\u0ec8\u0ead\u0ead\u0e81 = \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn * \u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0eaa\u0eb5\u0ea1<br \/>\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0e8d\u0eb7\u0e94\u0ead\u0eb2\u0e8d\u0eb8\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e87\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e9b\u0ecd\u0ec9\u0eb2, \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e82\u0eb1\u0e9a\u0e95\u0ec9\u0ead\u0e87\u0e9a\u0ecd\u0ec8\u0eaa\u0eb9\u0e87\u0e81\u0ea7\u0ec8\u0eb2 8 \u0e9a\u0eb2<\/p>\n<p><strong>\u0ea5\u0eb3\u0e94\u0eb1\u0e9a CZPT DLS \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec4\u0ea7\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7 CZPT (\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0ead\u0eb2\u0e81\u0eb2\u0e94) <\/strong><br \/><strong>CZPT- \u0e81\u0eb2\u0e99\u0ec0\u0e81\u0eb1\u0e9a\u0e81\u0eb3 DLS CZPT<\/strong><strong>(\u0e8d\u0eb9\u0ec9\u0e94\u0ec9\u0ea7\u0e8d\u0ead\u0eb2\u0e81\u0eb2\u0e94) \u0e8a\u0eb8\u0e94\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2 CZPT<\/strong><strong> <\/strong><br \/>CZPT- \u0e8a\u0eb8\u0e94\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2 CZPT (\u0ec0\u0e95\u0eb1\u0e81\u0ec2\u0e99\u0ec2\u0ea5\u0e8a\u0eb5\u0e9b\u0ecd\u0ec9\u0eb2\u0ec1\u0eab\u0ebc\u0ea7) \u0ec1\u0ea1\u0ec8\u0e99\u0ea7\u0eb4\u0e97\u0eb5\u0ec1\u0e81\u0ec9\u0ec4\u0e82\u0e97\u0eb5\u0ec8\u0e81\u0eb0\u0e97\u0eb1\u0e94\u0eae\u0eb1\u0e94 \u0ec1\u0ea5\u0eb0 \u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0ead\u0ec8\u0ead\u0e99 \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e9b\u0eb1\u0e9a\u0ec1\u0e95\u0ec8\u0e87\u0e95\u0eb2\u0ea1\u0eaa\u0eb0\u0ec0\u0e9b\u0eb1\u0e81\u0eaa\u0eb0\u0ec0\u0e9e\u0eb2\u0eb0\u0e82\u0ead\u0e87\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2\u0e94\u0ec9\u0ea7\u0e8d\u0e9b\u0ecd\u0ec9\u0eb2\u0ec1\u0eab\u0ebc\u0ea7\u0e97\u0eb5\u0ec8\u0e96\u0eb7\u0e81\u0e8d\u0eb9\u0ec9\u0e94\u0ec9\u0ea7\u0e8d\u0ea5\u0ebb\u0ea1 \u0e9e\u0ec9\u0ead\u0ea1\u0e97\u0eb1\u0e87\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0ec0\u0eaa\u0eb5\u0ea1\u0e97\u0eb1\u0e87\u0edd\u0ebb\u0e94\u0e97\u0eb5\u0ec8\u0e88\u0eb0\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87 \u0ec1\u0ea5\u0eb0 \u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0ec3\u0eaa\u0ec8\u0e81\u0ead\u0e9a \u0eab\u0ebc\u0eb7 \u0ec3\u0e99\u0e95\u0eb9\u0ec9\u0e9b\u0eb4\u0e94.<br \/>\u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec3\u0e8a\u0ec9\u0e87\u0eb2\u0e99\u0ec2\u0e9b\u0ea3\u0ec1\u0e81\u0ea3\u0ea1\u0e99\u0eb5\u0ec9, \u0e95\u0ec9\u0ead\u0e87\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea7\u0eb1\u0e94\u0ec1\u0e97\u0e81\u0ec1\u0eae\u0e87, \u0ea7\u0eb2\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ec3\u0eaa\u0ec8\u0ec1\u0e9c\u0e87\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1. \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0e84\u0ec8\u0eb2\u0ec4\u0e94\u0ec9\u0e87\u0ec8\u0eb2\u0e8d\u0e9c\u0ec8\u0eb2\u0e99\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e97\u0eb5\u0ec8\u0e87\u0ec8\u0eb2\u0e8d\u0e94\u0eb2\u0e8d. \u0e9b\u0ecd\u0ec9\u0eb2\u0e88\u0eb0\u0ea2\u0eb8\u0e94\u0ec2\u0e94\u0e8d\u0ead\u0eb1\u0e94\u0e95\u0eb0\u0ec2\u0e99\u0ea1\u0eb1\u0e94\u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0eaa\u0eb8\u0e94\u0e97\u0ec9\u0eb2\u0e8d\u0ea1\u0eb2\u0eae\u0ead\u0e94 \u0ec1\u0ea5\u0eb0 \u0e88\u0eb0\u0ec0\u0ea5\u0eb5\u0ec8\u0ea1\u0e95\u0ebb\u0ec9\u0e99\u0ec3\u0edd\u0ec8\u0e94\u0ec9\u0ea7\u0e8d\u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb8\u0e94\u0ea5\u0ebb\u0e87\u0ec0\u0ea5\u0eb1\u0e81\u0e99\u0ec9\u0ead\u0e8d\u0e82\u0ead\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81 \u0eab\u0ebc\u0eb7 \u0e81\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e82\u0eb6\u0ec9\u0e99\u0e82\u0ead\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e94\u0eb5\u0e99\u0e97\u0eb2\u0e87\u0e97\u0eb2\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94. \u0e8a\u0eb8\u0e94\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99 CZPT CZPT \u0ea1\u0eb5\u0ec3\u0eab\u0ec9\u0e9e\u0ec9\u0ead\u0ea1\u0e81\u0eb1\u0e9a\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0ec0\u0eae\u0eb1\u0e94\u0ec3\u0eab\u0ec9\u0e8a\u0eb8\u0e94\u0e9b\u0ecd\u0ec9\u0eb2\u0ec0\u0eab\u0ebc\u0ebb\u0ec8\u0eb2\u0e99\u0eb5\u0ec9\u0e94\u0eb5\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0eaa\u0eb0\u0edc\u0ead\u0e87\u0e9e\u0eb0\u0ea5\u0eb1\u0e87\u0e87\u0eb2\u0e99\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0e95\u0eb4\u0e9a\u0eb1\u0e94\u0e87\u0eb2\u0e99\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\/\u0ec4\u0eae\u0ec2\u0e94\u0ebc\u0ea5\u0eb4\u0e81\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0e8a\u0eb0\u0e99\u0eb4\u0e94. \u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94\u0ec0\u0e96\u0eb4\u0e87 640 MPa. <br \/>\u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb2\u0e81\u0ec1\u0eae\u0e87\u0e88\u0eb0\u0e96\u0eb7\u0e81\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e9b\u0ecd\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0ec3\u0e8a\u0ec9\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e99\u0eb4\u0ea7\u0ec0\u0ea1\u0e95\u0eb4\u0e81, \u0e81\u0eb2\u0e99\u0ec0\u0e8a\u0eb7\u0ec8\u0ead\u0ea1\u0e95\u0ecd\u0ec8\u0ec4\u0e9f\u0e9f\u0ec9\u0eb2\u0e88\u0eb6\u0ec8\u0e87\u0e9a\u0ecd\u0ec8\u0e88\u0eb3\u0ec0\u0e9b\u0eb1\u0e99. \u0ec0\u0e9e\u0eb7\u0ec8\u0ead\u0ec3\u0e8a\u0ec9\u0e87\u0eb2\u0e99\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e99\u0eb5\u0ec9, \u0e9b\u0ecd\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0e97\u0eb5\u0ec8\u0eaa\u0eb9\u0e9a\u0e94\u0ec9\u0ea7\u0e8d\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e95\u0ec9\u0ead\u0e87\u0ec4\u0e94\u0ec9\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0e95\u0ebb\u0ea7\u0e81\u0ead\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94 \u0ec1\u0ea5\u0eb0 \u0e95\u0ebb\u0ea7\u0ec1\u0e8d\u0e81\u0e99\u0ecd\u0ec9\u0eb2, \u0ea7\u0eb2\u0ea7\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea7\u0eb1\u0e94\u0ec1\u0e97\u0e81\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99 \u0ec1\u0ea5\u0eb0 \u0ea7\u0eb2\u0ea7\u0eab\u0ebc\u0eb8\u0e94\u0e9c\u0ec8\u0ead\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0ea1\u0eb7. \u0ec3\u0e99\u0e82\u0eb1\u0ec9\u0e99\u0e95\u0ead\u0e99\u0e99\u0eb5\u0ec9, \u0e9b\u0ecd\u0ec9\u0eb2\u0e88\u0eb0\u0e96\u0eb7\u0e81\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0ec3\u0eaa\u0ec8\u0e96\u0eb1\u0e87\u0ec0\u0eab\u0ebc\u0eb1\u0e81\u0eaa\u0eb0\u0ec1\u0e95\u0e99\u0ec0\u0ea5\u0e94\u0ec3\u0e99\u0e95\u0eb9\u0ec9\u0e9b\u0eb4\u0e94\u0ec3\u0e99\u0ec1\u0e9a\u0e9a\u0e97\u0eb5\u0ec8\u0e81\u0eb0\u0e97\u0eb1\u0e94\u0eae\u0eb1\u0e94 \u0ec1\u0ea5\u0eb0 \u0e9b\u0eb0\u0eab\u0e8d\u0eb1\u0e94\u0e9e\u0eb7\u0ec9\u0e99\u0e97\u0eb5\u0ec8. \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea7\u0eb1\u0e94\u0ec1\u0e97\u0e81\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99, \u0ea7\u0eb2\u0ea7 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0e94\u0eb1\u0e99\u0e88\u0eb0\u0e96\u0eb7\u0e81\u0e95\u0eb4\u0e94\u0e95\u0eb1\u0ec9\u0e87\u0ea2\u0eb9\u0ec8\u0ec0\u0e97\u0eb4\u0e87\u0ec1\u0e9c\u0e87\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1. <br \/>\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0ec3\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0eae\u0eb1\u0e94\u0ea7\u0ebd\u0e81\u0e97\u0eb5\u0ec8\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0e9a\u0eb1\u0e99\u0ea5\u0eb8\u0ec4\u0e94\u0ec9\u0ec2\u0e94\u0e8d\u0e81\u0eb2\u0e99\u0e94\u0eb1\u0e94\u0ec1\u0e9b\u0e87\u0ec1\u0eae\u0e87\u0e94\u0eb1\u0e99\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99. \u0ec0\u0ea1\u0eb7\u0ec8\u0ead\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e82\u0ead\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99 \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e82\u0ead\u0e87\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e9a\u0eb1\u0e99\u0ea5\u0eb8\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0ebb\u0ea1\u0e94\u0eb8\u0e99, \u0e9b\u0ecd\u0ec9\u0eb2\u0e88\u0eb0\u0ea2\u0eb8\u0e94\u0e81\u0eb2\u0e99\u0ec0\u0e95\u0eb5\u0ea1\u0ec0\u0e95\u0eb1\u0ea1\u0ec1\u0eae\u0e87 \u0ec1\u0ea5\u0eb0 \u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e82\u0ead\u0e87\u0e9c\u0ebb\u0e99\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e88\u0eb0\u0ea2\u0eb9\u0ec8\u0e97\u0eb5\u0ec8\u0e9c\u0ebb\u0e99\u0e9b\u0eb0\u0ec2\u0eab\u0e8d\u0e94\u0e97\u0eb5\u0ec8\u0e95\u0eb1\u0ec9\u0e87\u0ec4\u0ea7\u0ec9\u0ea5\u0ec8\u0ea7\u0e87\u0edc\u0ec9\u0eb2. \u0edc\u0ec8\u0ea7\u0e8d\u0ec4\u0eae\u0ec2\u0e94\u0ebc\u0ea5\u0eb4\u0e81\u0e99\u0eb5\u0ec9\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ec3\u0e8a\u0ec9\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ea1\u0eb7\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87 \u0ec1\u0ea5\u0eb0 \u0e97\u0ebb\u0e94\u0eaa\u0ead\u0e9a\u0e97\u0eb8\u0e81\u0e9b\u0eb0\u0ec0\u0e9e\u0e94\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0eaa\u0eb0\u0e96\u0eb2\u0e9a\u0eb1\u0e99\u0e81\u0eb2\u0e99\u0eaa\u0eb6\u0e81\u0eaa\u0eb2 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a \u0eab\u0ebc\u0eb7 \u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e84\u0ea7\u0eb2\u0ea1\u0eaa\u0eb2\u0ea1\u0eb2\u0e94\u0ead\u0eb7\u0ec8\u0e99\u0ec6\u0e97\u0eb5\u0ec8\u0e95\u0ec9\u0ead\u0e87\u0e81\u0eb2\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87\u0e97\u0eb5\u0ec8\u0ea5\u0eb0\u0e9a\u0eb8\u0ec4\u0e94\u0ec9.\u00a0<\/p>\n<p><strong>\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0e82\u0ead\u0e87 CZPT \u0ec2\u0e95\u0eb0\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb2\u0e99\u0ec0\u0e81\u0eb1\u0e9a\u0ec0\u0e87\u0eb4\u0e99 DLS-DGG<\/strong><br \/>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>\u0e81\u0eb2\u0e99\u0ead\u0ead\u0e81\u0ec1\u0e9a\u0e9a<\/td>\n<td>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87<\/td>\n<td>\u0e81\u0ead\u0e87\u0e97\u0eb1\u0e9a\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn P<sub>\u0ea5<\/sub> <\/td>\n<td>\u0ea7\u0eb4\u0e97\u0eb5\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0e99\u0ebb\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0ead\u0e81<\/td>\n<td>MAX Outlet<br \/>\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87 (\u0e9a\u0eb2)*<\/td>\n<td>CZPTn <br \/>\u0e97\u0ec8\u0eb2\u0e97\u0eb2\u0e87\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ead\u0eb2\u0e81\u0eb2\u0e94 <br \/>\u00a0<\/td>\n<td>\u0e9e\u0ead\u0e94\u0ead\u0ead\u0e81\u0ec1\u0eae\u0e87\u0eaa\u0eb9\u0e87<\/td>\n<td>\u0e81\u0eb0\u0ec1\u0eaa\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94<br \/>(\u0ea5\u0eb4\u0e94\/\u0e99\u0eb2\u0e97\u0eb5)**<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGGD4<\/td>\n<td>4:1<\/td>\n<td>\u0eaa\u0eb2\u0ea1\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>4XP<sub>\u0ea5<\/sub><\/td>\n<td>32<\/td>\n<td>G 1\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>70.<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG6<\/td>\n<td>6:1<\/td>\n<td>3-8 \u0e9a\u0eb2<\/td>\n<td>6XP<sub>\u0ea5<\/sub><\/td>\n<td>\u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0ec1\u0e9b\u0e94<\/td>\n<td>G 1\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>29.91<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG10<\/td>\n<td>\u0eaa\u0eb4\u0e9a:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0eb2\u0ea1-8 \u0e9a\u0eb2<\/td>\n<td>10XP<sub>\u0ea5<\/sub><\/td>\n<td>80<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>18.\u0ec1\u0e9b\u0e94\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG16<\/td>\n<td>16:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0eb2\u0ea1-8 \u0e9a\u0eb2<\/td>\n<td>16XP<sub>\u0ea5<\/sub><\/td>\n<td>128<\/td>\n<td>G 1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>12. \u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0eaa\u0ead\u0e87<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG28<\/td>\n<td>28:1<\/td>\n<td>3-8 \u0e9a\u0eb2<\/td>\n<td>28XP<sub>\u0ea5<\/sub><\/td>\n<td>224<\/td>\n<td>G 1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>\u0ec0\u0e8a\u0ec0\u0ea7\u0eb1\u0e99.\u0ead\u0eb5\u0ec0\u0ea5\u0ec0\u0ea7\u0eb1\u0e99<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG40<\/td>\n<td>40:1<\/td>\n<td>\u0eaa\u0eb2\u0ea1-8 \u0e9a\u0eb2<\/td>\n<td>40XP<sub>\u0ea5<\/sub><\/td>\n<td>320<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>4.89<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG64<\/td>\n<td>\u0eab\u0ebb\u0e81\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0eb2\u0ea1\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>64XP<sub>\u0ea5<\/sub><\/td>\n<td>512<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>3.08<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG80<\/td>\n<td>80:1<\/td>\n<td>\u0eaa\u0eb2\u0ea1\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>80XP<sub>\u0ea5<\/sub><\/td>\n<td>640<\/td>\n<td>G 1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>2.44<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG100<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d: \u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>3-8 \u0e9a\u0eb2<\/td>\n<td>100XP<sub>\u0ea5<\/sub><\/td>\n<td>800<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>1.92<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG130<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d\u0eaa\u0eb2\u0ea1\u0eaa\u0eb4\u0e9a:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>3-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>130XP<sub>\u0ea5<\/sub><\/td>\n<td>1040<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>1.47<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG175<\/td>\n<td>175:1<\/td>\n<td>3-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>175XP<sub>\u0ea5<\/sub><\/td>\n<td>1400<\/td>\n<td>G 1\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>1.14<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG255<\/td>\n<td>255:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>3-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>255XP<sub>\u0ea5<\/sub><\/td>\n<td>2040<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>.75<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG400<\/td>\n<td>\u0eaa\u0eb5\u0ec8\u0eae\u0ec9\u0ead\u0e8d:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>3-8 \u0e9a\u0eb2<\/td>\n<td>400XP<sub>\u0ea5<\/sub><\/td>\n<td>3200<\/td>\n<td>G 1\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>.48<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG510<\/td>\n<td>510:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0eb2\u0ea1\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>510XP<sub>\u0ea5<\/sub><\/td>\n<td>4080<\/td>\n<td>G 1\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>.\u0eab\u0ebb\u0e81\u0eaa\u0eb4\u0e9a\u0eab\u0ec9\u0eb2<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGG800<\/td>\n<td>800:1<\/td>\n<td>\u0eaa\u0eb2\u0ea1-8 \u0e9a\u0eb2<\/td>\n<td>800XP<sub>\u0ea5<\/sub><\/td>\n<td>6400<\/td>\n<td>G 1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>.42<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd\u0e94\u0e82\u0ead\u0e87 CZPT \u0ec2\u0e95\u0eb0\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb2\u0e99\u0ec0\u0e81\u0eb1\u0e9a\u0ec0\u0e87\u0eb4\u0e99 DLS-M<\/strong><br \/>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99<\/td>\n<td>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0eaa\u0ec8\u0ea7\u0e99\u0e81\u0eb2\u0e99\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e84\u0eb1\u0ec8\u0e87\u0e95\u0eb6\u0e87<\/td>\n<td>\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0e97\u0eb2\u0e87\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn P<sub>\u0ea5<\/sub> <\/td>\n<td>\u0ea5\u0eb0\u0e9a\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0e9b\u0eb0\u0ec0\u0ea1\u0eb5\u0e99\u0ec1\u0eae\u0e87\u0ead\u0ead\u0e81<\/td>\n<td>MAX Outlet<br \/>\u0ec1\u0eae\u0e87 (\u0e9a\u0eb2)*<\/td>\n<td>CZPTn <br \/>\u0e97\u0ec8\u0eb2\u0e97\u0eb2\u0e87\u0ec0\u0e82\u0ebb\u0ec9\u0eb2\u0ead\u0eb2\u0e81\u0eb2\u0e94 <br \/>\u00a0<\/td>\n<td>\u0eae\u0eb9\u0eaa\u0ebd\u0e9a\u0ead\u0ead\u0e81\u0ec1\u0eae\u0e87\u0e94\u0eb1\u0e99\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec3\u0eab\u0e8d\u0ec8<\/td>\n<td>\u0ead\u0eb1\u0e94\u0e95\u0eb2\u0e81\u0eb2\u0e99\u0ec4\u0eab\u0ebc\u0eaa\u0eb9\u0e87\u0eaa\u0eb8\u0e94 (\u0ea5\u0eb4\u0e94\/\u0e99\u0eb2\u0e97\u0eb5)**<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM4<\/td>\n<td>\u0eaa\u0eb5\u0ec8:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0eb2\u0ea1-8 \u0e9a\u0eb2<\/td>\n<td>4XP<sub>\u0ea5<\/sub><\/td>\n<td>32<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>15.36<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM100<\/td>\n<td>10:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>3-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>10XP<sub>\u0ea5<\/sub><\/td>\n<td>80<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>7.15<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM16<\/td>\n<td>16:1<\/td>\n<td>3-8 \u0e9a\u0eb2<\/td>\n<td>16XP<sub>\u0ea5<\/sub><\/td>\n<td>128<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>\u0eaa\u0eb5\u0ec8.59<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM30<\/td>\n<td>30:1<\/td>\n<td>3-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>30XP<sub>\u0ea5<\/sub><\/td>\n<td>240<\/td>\n<td>G 1\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>\u0eaa\u0ead\u0e87. \u0eab\u0ec9\u0eb2\u0eaa\u0eb4\u0e9a\u0eaa\u0eb2\u0ea1<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM44<\/td>\n<td>44:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0eb2\u0ea1\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>44XP<sub>\u0ea5<\/sub><\/td>\n<td>352<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87. \u0eaa\u0eb5\u0ec8\u0eaa\u0eb4\u0e9a\u0ec0\u0ead\u0eb1\u0e94<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM64<\/td>\n<td>\u0eab\u0ebb\u0e81\u0eaa\u0eb4\u0e9a\u0eaa\u0eb5\u0ec8:\u0edc\u0eb6\u0ec8\u0e87<\/td>\n<td>\u0eaa\u0eb2\u0ea1\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>64XP<sub>\u0ea5<\/sub><\/td>\n<td>512<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>.\u0ec0\u0e81\u0ebb\u0ec9\u0eb2\u0eaa\u0eb4\u0e9a\u0eab\u0ec9\u0eb2<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM100<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d:1<\/td>\n<td>\u0eaa\u0eb2\u0ea1-8 \u0e9a\u0eb2<\/td>\n<td>100XP<sub>\u0ea5<\/sub><\/td>\n<td>800<\/td>\n<td>G \u0edc\u0eb6\u0ec8\u0e87\/2<\/td>\n<td>NPT\/ZG<\/td>\n<td>.64<\/td>\n<\/tr>\n<tr>\n<td>DLS-DGM170<\/td>\n<td>\u0edc\u0eb6\u0ec8\u0e87\u0eae\u0ec9\u0ead\u0e8d\u0ec0\u0e88\u0eb1\u0e94\u0eaa\u0eb4\u0e9a:1<\/td>\n<td>3-\u0ec1\u0e9b\u0e94\u0e9a\u0eb2<\/td>\n<td>170XP<sub>\u0ea5<\/sub><\/td>\n<td>1360<\/td>\n<td>G 1\/\u0eaa\u0ead\u0e87<\/td>\n<td>NPT\/ZG<\/td>\n<td>.37<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94 CZPT \u0e88\u0eb3\u0e81\u0eb1\u0e94 \u0ec1\u0ea1\u0ec8\u0e99\u0eaa\u0eb0\u0ea1\u0eb2\u0e8a\u0eb4\u0e81\u0e82\u0ead\u0e87\u0e97\u0eb5\u0ea1\u0e87\u0eb2\u0e99 CZPT \u0ec0\u0e8a\u0eb4\u0ec8\u0e87\u0e95\u0eb1\u0ec9\u0e87\u0ea2\u0eb9\u0ec8\u0ec3\u0e99\u0ec0\u0ea1\u0eb7\u0ead\u0e87\u0eab\u0eb2\u0e87\u0ec2\u0e88\u0ea7 \u0ec1\u0e82\u0ea7\u0e87\u0ec0\u0e88\u0eb5\u0ec9\u0e88\u0ebd\u0e87 \u0e9b\u0eb0\u0ec0\u0e97\u0e94\u0e88\u0eb5\u0e99. \u0e94\u0ec9\u0ea7\u0e8d\u0e9b\u0eb0\u0eaa\u0ebb\u0e9a\u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb2\u0e8d\u0e81\u0ea7\u0ec8\u0eb2 15 \u0e9b\u0eb5\u0ec3\u0e99\u0e82\u0eb0\u0ec1\u0edc\u0e87\u0e81\u0eb2\u0e99\u0ec1\u0ea5\u0e81\u0e9b\u0ec8\u0ebd\u0e99\u0e84\u0ea7\u0eb2\u0ea1\u0e81\u0ebb\u0e94\u0e94\u0eb1\u0e99\u0e82\u0ead\u0e87\u0e99\u0ecd\u0ec9\u0eb2 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e84\u0ea7\u0e9a\u0e84\u0eb8\u0ea1, \u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0eaa\u0eb0\u0ec0\u0edc\u0eb5\u0e9b\u0ecd\u0ec9\u0eb2\u0ec0\u0eaa\u0eb5\u0ea1\u0ec1\u0e9a\u0e9a\u0e99\u0eb4\u0ea7\u0ec0\u0ea1\u0e95\u0eb4\u0e81 \u0ec1\u0ea5\u0eb0 \u0ec4\u0eae\u0ec2\u0e94\u0ebc\u0ea5\u0eb4\u0e81\u0eab\u0ebc\u0eb2\u0e81\u0eab\u0ebc\u0eb2\u0e8d\u0e8a\u0eb0\u0e99\u0eb4\u0e94, \u0ea5\u0eb0\u0e9a\u0ebb\u0e9a \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0ec3\u0eab\u0ec9\u0e81\u0eb1\u0e9a\u0ea5\u0eb9\u0e81\u0e84\u0ec9\u0eb2\u0e97\u0ebb\u0ec8\u0ea7\u0ec2\u0ea5\u0e81. \u0ec0\u0e99\u0eb7\u0ec8\u0ead\u0e87\u0e88\u0eb2\u0e81\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99\u0e97\u0eb5\u0ec8\u0e94\u0eb5\u0e97\u0eb5\u0ec8\u0eaa\u0eb8\u0e94\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0ea1\u0eb5\u0e84\u0eb8\u0e99\u0e99\u0eb0\u0e9e\u0eb2\u0e9a\u0e94\u0eb5, \u0ea5\u0eb2\u0e84\u0eb2\u0e97\u0eb5\u0ec8\u0ec0\u0edd\u0eb2\u0eb0\u0eaa\u0ebb\u0ea1 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0eab\u0ebc\u0eb1\u0e87\u0e81\u0eb2\u0e99\u0e82\u0eb2\u0e8d\u0e97\u0eb5\u0ec8\u0e94\u0eb5\u0ec0\u0ea5\u0eb5\u0e94, \u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0e88\u0eb6\u0ec8\u0e87\u0ea1\u0eb5\u0e9b\u0eb0\u0eab\u0ea7\u0eb1\u0e94\u0e84\u0ea7\u0eb2\u0ea1\u0ec0\u0e9b\u0eb1\u0e99\u0ea1\u0eb2\u0e97\u0eb5\u0ec8\u0e94\u0eb5\u0ec0\u0ea5\u0eb5\u0e94\u0ec3\u0e99\u0e82\u0eb0\u0ec1\u0edc\u0e87\u0e81\u0eb2\u0e99\u0e99\u0eb5\u0ec9.<br \/>\u00a0<br \/><strong>\u0eaa\u0eb4\u0e99\u0e84\u0ec9\u0eb2\u0eab\u0ebc\u0eb1\u0e81\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2\u0e84\u0eb7:<\/strong><br \/>\u0e9b\u0ecd\u0ec9\u0eb2\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0ec1\u0eae\u0e87 (\u0e9b\u0ecd\u0ec9\u0eb2\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0ead\u0eb2\u0e8d\u0ec1\u0e81\u0eb1\u0eaa\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn, \u0e9b\u0ecd\u0ec9\u0eb2\u0ec1\u0eab\u0ebc\u0ea7\u0ead\u0eb2\u0e81\u0eb2\u0e94 CZPTn, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e82\u0eb0\u0eab\u0e8d\u0eb2\u0e8d\u0ead\u0eb2\u0e81\u0eb2\u0e94)<br \/>\u0ec2\u0e84\u0e87\u0e81\u0eb2\u0e99\u0e81\u0eb3\u0ea5\u0eb1\u0e87\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec3\u0eab\u0e8d\u0ec8 (\u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0eb5\u0ec0\u0e9e\u0eb5\u0ec8\u0ea1\u0e99\u0ecd\u0ec9\u0eb2\u0ea1\u0eb1\u0e99\u0ec0\u0e8a\u0eb7\u0ec9\u0ead\u0ec4\u0e9f\/\u0e82\u0ead\u0e87\u0ec1\u0eab\u0ebc\u0ea7, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0ec0\u0e95\u0eb5\u0ea1 FM200, \u0e81\u0eb2\u0e99\u0e9b\u0eb9\u0e81\u0e97\u0ecd\u0ec8 CZPT)<br \/>\u0ead\u0eb8\u0e9b\u0eb0\u0e81\u0ead\u0e99\u0e97\u0ebb\u0e94\u0eaa\u0ead\u0e9a\u0ec1\u0eae\u0e87\u0e82\u0eb0\u0edc\u0eb2\u0e94\u0ec3\u0eab\u0e8d\u0ec8 CZPT (CZPT\/Burst\/Hydrostatic, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e81\u0ea7\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb0\u0e9a\u0ead\u0e81\u0eaa\u0eb9\u0e9a,<br \/>(\u0ea7\u0eb2\u0ea7\u0e9e\u0eb4\u0e88\u0eb2\u0ea5\u0eb0\u0e99\u0eb2\u0ec0\u0e9a\u0eb4\u0ec8\u0e87\u0ec2\u0e95\u0eb0, \u0e81\u0eb2\u0e99\u0e81\u0ea7\u0e94\u0e88\u0eb1\u0e9a\u0ec1\u0e9a\u0e9a\u0e81\u0eb0\u0e95\u0eb8\u0ec9\u0e99 CZPT, \u0ec1\u0ea5\u0eb0\u0ead\u0eb7\u0ec8\u0e99\u0ec6.)<br \/>\u00a0<br \/><strong>\u0e84\u0ecd\u0eb2\u0eae\u0ec9\u0ead\u0e87\u0eaa\u0eb0\u0eab\u0ea1\u0eb1\u0e81\u0e9c\u0eb0\u0ea5\u0eb4\u0e94\u0e95\u0eb0\u0e9e\u0eb1\u0e99<\/strong><br \/>\u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99 CZPT, \u0e99\u0ec9\u0eb3\u0ea1\u0eb1\u0e99\u0ec1\u0ead\u0eb1\u0e94\u0e8a\u0eb1\u0e87 CZPT, CZPT CZPT, \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e94\u0eb1\u0e9a\u0ec0\u0e9e\u0eb5\u0e87, \u0eaa\u0eb0\u0e96\u0eb2\u0e99\u0e97\u0eb5\u0ec8\u0eaa\u0eb7\u0e9a\u0eaa\u0ea7\u0e99 \u0ec1\u0ea5\u0eb0 \u0ead\u0eb7\u0ec8\u0e99\u0ec6.<br \/>\u00a0<br \/><strong>\u0e81\u0eb2\u0e99\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e82\u0ead\u0e87\u0e9e\u0ea7\u0e81\u0ec0\u0eae\u0ebb\u0eb2<\/strong><br \/>\u0eae\u0eb1\u0e9a\u0e9b\u0eb0\u0e81\u0eb1\u0e99\u0e9f\u0ea3\u0eb5 13 \u0ec0\u0e94\u0eb7\u0ead\u0e99 \u0e99\u0eb1\u0e9a\u0e95\u0eb1\u0ec9\u0e87\u0ec1\u0e95\u0ec8\u0ea1\u0eb7\u0ec9\u0e8a\u0eb7\u0ec9 \u0ec1\u0ea5\u0eb0 \u0e81\u0eb2\u0e99\u0e8a\u0ec8\u0ea7\u0e8d\u0ec0\u0eab\u0ebc\u0eb7\u0ead\u0e94\u0ec9\u0eb2\u0e99\u0ec0\u0e97\u0eb1\u0e81\u0ec2\u0e99\u0ec2\u0ea5\u0ea2\u0eb5\u0ec2\u0e94\u0e8d\u0e9a\u0ecd\u0ec8\u0ec0\u0eaa\u0e8d\u0e84\u0ec8\u0eb2\u0e95\u0eb0\u0eab\u0ebc\u0ead\u0e94\u0ead\u0eb2\u0e8d\u0eb8\u0e81\u0eb2\u0e99\u0ec3\u0e8a\u0ec9\u0e87\u0eb2\u0e99<\/p>\n<p>\u00a0                            <\/p>\n<p>\n<p><img decoding=\"async\" style=\"height:auto\" title=\"\u0eae\u0eb8\u0ec8\u0e99\u0e8d\u0eb5\u0ec8\u0eab\u0ecd\u0ec9 Suncenter \u0e82\u0eb2\u0e8d\u0e94\u0eb5: Dgg28 28: 1 \u0e9b\u0ecd\u0ec9\u0eb2\u0e99\u0ecd\u0ec9\u0eb2\u0e82\u0eb1\u0e9a\u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e99\u0e94\u0ec9\u0ea7\u0e8d\u0ea5\u0ebb\u0ea1\u0eaa\u0eb3\u0ea5\u0eb1\u0e9a\u0e81\u0eb2\u0e99\u0e97\u0ebb\u0e94\u0eaa\u0ead\u0e9a\u0e81\u0eb2\u0e99\u0ea5\u0eb0\u0ec0\u0e9a\u0eb5\u0e94\" src=\"http:\/\/img.hzpt.com\/uploads\/images\/ZHMedical\/Vacuum-pump-5.jpg\" alt=\"Hot Sale Suncenter Brand Model: Dgg28 28: 1 Pneumatic Driven Liquid Pump for Burst Testing\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Sizzling sale CZPT brand Product: DGG28 \u00a028:one CZPT driven liquid pump for burst testingWe offer you the most complete variety of Air pushed liquid pump versions in the market measured for: Capacity of final pressure, movement or output horsepower. Compatibility with a broad selection of liquids, these kinds of as oil, drinking water and chemical [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-806","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/posts\/806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/comments?post=806"}],"version-history":[{"count":0,"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/posts\/806\/revisions"}],"wp:attachment":[{"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/media?parent=806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/categories?post=806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pistonpumps.top\/lo\/wp-json\/wp\/v2\/tags?post=806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}