{"id":2789,"count":1,"description":"","link":"https:\/\/pistonpumps.top\/th\/tag\/stainless-screw\/","name":"\u0e2a\u0e01\u0e23\u0e39\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a","slug":"stainless-screw","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/pistonpumps.top\/th\/wp-json\/wp\/v2\/tags\/2789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pistonpumps.top\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pistonpumps.top\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pistonpumps.top\/th\/wp-json\/wp\/v2\/posts?tags=2789"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}